{"id":3250,"date":"2016-11-21T10:30:33","date_gmt":"2016-11-21T08:30:33","guid":{"rendered":"http:\/\/www.expomaquinaria.es\/wpblog\/?p=3250"},"modified":"2016-11-21T10:31:31","modified_gmt":"2016-11-21T08:31:31","slug":"arcon-congelador","status":"publish","type":"post","link":"https:\/\/www.expomaquinaria.es\/wpblog\/2016\/11\/21\/arcon-congelador\/","title":{"rendered":"Arc\u00f3n congelador"},"content":{"rendered":"<h1 style=\"text-align: justify;\">Cosas a\u00a0tener en cuenta antes de comprar un arc\u00f3n Congelador<\/h1>\n<p style=\"text-align: justify;\">A la hora de elegir un arc\u00f3n congelador nos deja un mont\u00f3n de inc\u00f3gnitas por eso os traigo una serie de par\u00e1metros a tener en cuenta a la hora de comprar un arc\u00f3n congelador.<\/p>\n<h3 style=\"text-align: justify;\">Tama\u00f1o<\/h3>\n<p style=\"text-align: justify;\">Este punto es esencial ya que necesitamos un arc\u00f3n congelador que cubra nuestras necesidad sin necesidad de pasarse o quedarse corto.<\/p>\n<p style=\"text-align: justify;\">Uno demasiado grande que no se llene seria un derroche energ\u00e9tico, adem\u00e1s podr\u00eda acumularse escarcha.<\/p>\n<p style=\"text-align: justify;\">En cambio, uno peque\u00f1o no cubrir\u00eda nuestras necesidades, por lo tanto necesitar\u00edamos comprar otro y terminar\u00edamos gastando el doble tanto en\u00e9rgicamente como\u00a0de espacio, claramente todo esto repercutir\u00eda en nuestro bolsillo.<\/p>\n<h3 style=\"text-align: justify;\">Estilo<\/h3>\n<p style=\"text-align: justify;\">Hay tres tipos de Arcones congeladores:<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.expomaquinaria.es\/796-arcones-congeladores-tapa-abatible\">Arcones congeladores de tapa abatible<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.expomaquinaria.es\/795-arcones-congeladores-tapa-corredera\">Arcones congeladores de tapa corredera<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.expomaquinaria.es\/794-congeladores-para-supermercado\">Congeladores para supermercado<\/a><\/p>\n<p style=\"text-align: justify;\">Tenemos que pensar cual de ellos nos har\u00eda mejor papel y elegir con cabeza. Obviamente no vas a poner en un supermercado un congelador de tapa abatible o en un restaurante un congelador de supermercado. Cada congelador tiene un uso y hay que ser acordes con ello.<\/p>\n<h3 style=\"text-align: justify;\">Instalaci\u00f3n<\/h3>\n<p style=\"text-align: justify;\">Hay que fijarse en la instalaci\u00f3n el\u00e9ctrica que tenemos y comprar un arc\u00f3n congelador en base a eso, ya que no queremos cortes de luz repentinos o utilizar un sistema auxiliar para controlar la energ\u00eda.<\/p>\n<h3><a href=\"http:\/\/www.expomaquinaria.es\/796-arcones-congeladores-tapa-abatible\"><strong>Arcones congeladores de tapa abatible<\/strong><\/a><\/h3>\n<p><a href=\"http:\/\/www.expomaquinaria.es\/arcones-congeladores-tapa-abatible\/2818-arcon-congelador-atch110.html\"><strong>ARC\u00d3N CONGELADOR 106 L. PUERTA ABATIBLE<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.expomaquinaria.es\/arcones-congeladores-tapa-abatible\/2818-arcon-congelador-atch110.html\"><img decoding=\"async\" class=\"aligncenter wp-image-3255 size-full\" title=\"arcon puerta abatible\" src=\"http:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/arcon-congelador-atch110.jpg\" alt=\"arcon puerta abatible\" width=\"459\" height=\"521\" srcset=\"https:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/arcon-congelador-atch110.jpg 459w, https:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/arcon-congelador-atch110-264x300.jpg 264w\" sizes=\"(max-width: 459px) 100vw, 459px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">En primer lugar, este arc\u00f3n congelador tiene term\u00f3metro analogico, regulable y con condensador de ventilaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Tiene un volumen \u00fatil de 106 litros<\/p>\n<p style=\"text-align: justify;\">Sus medidas son:\u00a055x65x85CM<\/p>\n<h3><a href=\"http:\/\/www.expomaquinaria.es\/795-arcones-congeladores-tapa-corredera\">Arcones congeladores de tapa corredera<\/a><\/h3>\n<p><a href=\"http:\/\/www.expomaquinaria.es\/congeladores-para-supermercado\/5312-arcon-congelador-puerta-corredera-cmgt2000.html\"><strong>ARC\u00d3N CONGELADOR 674L. P.CORREDERA CRISTAL 205X96X78 CM<\/strong><\/a><\/p>\n<p><a href=\"http:\/\/www.expomaquinaria.es\/congeladores-para-supermercado\/5312-arcon-congelador-puerta-corredera-cmgt2000.html\"><img decoding=\"async\" class=\"aligncenter wp-image-3256 size-full\" title=\"arcon de puerta corredera\" src=\"http:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/arcon-congelador-puerta-corredera-cmgt2000.jpg\" alt=\"arcon-congelador-puerta-corredera-cmgt2000\" width=\"800\" height=\"800\" srcset=\"https:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/arcon-congelador-puerta-corredera-cmgt2000.jpg 800w, https:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/arcon-congelador-puerta-corredera-cmgt2000-150x150.jpg 150w, https:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/arcon-congelador-puerta-corredera-cmgt2000-300x300.jpg 300w, https:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/arcon-congelador-puerta-corredera-cmgt2000-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Este arc\u00f3n congelador de puerta corredera viene con 2 cestos de dotaci\u00f3n (Se le pueden a\u00f1adir un m\u00e1ximo de 12 cestos)<\/p>\n<p style=\"text-align: justify;\">Tiene un consumo de energ\u00eda de 6KW\/24h<\/p>\n<p style=\"text-align: justify;\">Teniendo una capacidad de 674 litros<\/p>\n<p style=\"text-align: justify;\">Sus medidas son:\u00a0205 x 96 x 78 cm<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, cuenta con un cuadro de mandos dispuesto de termostato, term\u00f3metro anal\u00f3gico, interruptor de encendido, interruptor cong. r\u00e1pida y un piloto de alarma.<\/p>\n<h3><strong><a href=\"http:\/\/www.expomaquinaria.es\/794-congeladores-para-supermercado\">Congeladores para supermercado<\/a><\/strong><\/h3>\n<p><a href=\"http:\/\/www.expomaquinaria.es\/congeladores-para-supermercado\/5284-congelador-supermercado-inche1770tc.html\"><strong>ARCON CONGELADOR 370L. P. DE CRISTAL 182.8X84X90 CM<\/strong><\/a><\/p>\n<p><a href=\"http:\/\/www.expomaquinaria.es\/congeladores-para-supermercado\/5284-congelador-supermercado-inche1770tc.html\"><img decoding=\"async\" class=\"aligncenter wp-image-3259 size-full\" title=\"congelador supermercado\" src=\"http:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/congelador-supermercado-inche1770tc-1.jpg\" alt=\"congelador supermercado\" width=\"800\" height=\"800\" srcset=\"https:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/congelador-supermercado-inche1770tc-1.jpg 800w, https:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/congelador-supermercado-inche1770tc-1-150x150.jpg 150w, https:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/congelador-supermercado-inche1770tc-1-300x300.jpg 300w, https:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/congelador-supermercado-inche1770tc-1-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Para finalizar, una\u00a0particularidad de los arcones congeladores de supermercado es que tienen vitrina y puertas de cristal para que podamos ver su interior.<\/p>\n<p style=\"text-align: justify;\">Sus medidas son:\u00a0182.8 x 84 x 90 cm<\/p>\n<p style=\"text-align: justify;\">Tiene una potencia de 762W<\/p>\n<p style=\"text-align: justify;\">Con una capacidad de 370 litros<\/p>\n<p style=\"text-align: justify;\">Sobre todo, su condensaci\u00f3n es ventilada y evaporaci\u00f3n est\u00e1tica en tuber\u00eda de cobre.<\/p>\n<p><a href=\"http:\/\/www.expomaquinaria.es\/390-arcon-congelador\"><img decoding=\"async\" class=\"aligncenter wp-image-3258 size-full\" title=\"catalogo-arcones-congeladores\" src=\"http:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/catalogo-arcones-congeladores.jpg\" alt=\"catalogo-arcones-congeladores\" width=\"850\" height=\"160\" srcset=\"https:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/catalogo-arcones-congeladores.jpg 850w, https:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/catalogo-arcones-congeladores-300x56.jpg 300w, https:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/catalogo-arcones-congeladores-768x145.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a><\/p>\n<blockquote>\n<p style=\"text-align: center;\">Autor: Raquel Ruesca Saiz \u2013 CM Expomaquinaria \u2013 2016<\/p>\n<p style=\"text-align: center;\">Prohibida la reproducci\u00f3n total o parcial sin autorizaci\u00f3n expresa de Expomaquinaria IRC S.L.<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Cosas a\u00a0tener en cuenta antes de comprar un arc\u00f3n Congelador A la hora de elegir un arc\u00f3n congelador nos deja un mont\u00f3n de inc\u00f3gnitas por eso os traigo una serie de par\u00e1metros a tener en cuenta a la hora de comprar un arc\u00f3n congelador. Tama\u00f1o Este punto es esencial ya que necesitamos un arc\u00f3n congelador [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3259,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[410,411,414,415,413,412],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arc\u00f3n congelador - Blog bar - Secretos de Hosteler\u00eda<\/title>\n<meta name=\"description\" content=\"Arc\u00f3n congelador - Las mejores ofertas de arcones congeladores. Te ayudamos a elegir tu arc\u00f3n congelador!! Consejos b\u00e1sicos para elegir el arc\u00f3n perfecto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.expomaquinaria.es\/wpblog\/2016\/11\/21\/arcon-congelador\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arc\u00f3n congelador - Blog bar - Secretos de Hosteler\u00eda\" \/>\n<meta property=\"og:description\" content=\"Arc\u00f3n congelador - Las mejores ofertas de arcones congeladores. Te ayudamos a elegir tu arc\u00f3n congelador!! Consejos b\u00e1sicos para elegir el arc\u00f3n perfecto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.expomaquinaria.es\/wpblog\/2016\/11\/21\/arcon-congelador\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog hosteleria - Secretos de Hosteler\u00eda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/expomaquinaria\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/expomaquinaria\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-21T08:30:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-11-21T08:31:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/congelador-supermercado-inche1770tc-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"expomaquinaria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/expomaquinaria\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"expomaquinaria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/www.expomaquinaria.es\/wpblog\/2016\/11\/21\/arcon-congelador\/\",\"url\":\"https:\/\/www.expomaquinaria.es\/wpblog\/2016\/11\/21\/arcon-congelador\/\",\"name\":\"Arc\u00f3n congelador - Blog bar - Secretos de Hosteler\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/www.expomaquinaria.es\/wpblog\/#website\"},\"datePublished\":\"2016-11-21T08:30:33+00:00\",\"dateModified\":\"2016-11-21T08:31:31+00:00\",\"author\":{\"@id\":\"https:\/\/www.expomaquinaria.es\/wpblog\/#\/schema\/person\/f46f0b99f244d0a6664d217d9fef2423\"},\"description\":\"Arc\u00f3n congelador - Las mejores ofertas de arcones congeladores. Te ayudamos a elegir tu arc\u00f3n congelador!! Consejos b\u00e1sicos para elegir el arc\u00f3n perfecto.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.expomaquinaria.es\/wpblog\/2016\/11\/21\/arcon-congelador\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.expomaquinaria.es\/wpblog\/2016\/11\/21\/arcon-congelador\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.expomaquinaria.es\/wpblog\/2016\/11\/21\/arcon-congelador\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.expomaquinaria.es\/wpblog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arc\u00f3n congelador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.expomaquinaria.es\/wpblog\/#website\",\"url\":\"https:\/\/www.expomaquinaria.es\/wpblog\/\",\"name\":\"Blog hosteleria - Secretos de Hosteler\u00eda\",\"description\":\"Blog hosteleria, Art\u00edculos y noticias del mundo de la hosteler\u00eda y comercio\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.expomaquinaria.es\/wpblog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.expomaquinaria.es\/wpblog\/#\/schema\/person\/f46f0b99f244d0a6664d217d9fef2423\",\"name\":\"expomaquinaria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.expomaquinaria.es\/wpblog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b949b2428b2d8f2987d91552b839aaf?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b949b2428b2d8f2987d91552b839aaf?s=96&d=identicon&r=g\",\"caption\":\"expomaquinaria\"},\"description\":\"Expomaquinaria - \\\"Pasi\u00f3n por la Hosteler\u00eda\\\", somos un conjunto de profesionales con mas de 30 a\u00f1os de experiencia en el sector de la hosteler\u00eda y comercio. Nos gusta nuestro trabajo y siempre estamos dispuestos a escucharte y asesorarte en lo que necesites.\",\"sameAs\":[\"https:\/\/www.expomaquinaria.es\",\"https:\/\/www.facebook.com\/expomaquinaria\",\"https:\/\/twitter.com\/https:\/\/twitter.com\/expomaquinaria\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arc\u00f3n congelador - Blog bar - Secretos de Hosteler\u00eda","description":"Arc\u00f3n congelador - Las mejores ofertas de arcones congeladores. Te ayudamos a elegir tu arc\u00f3n congelador!! Consejos b\u00e1sicos para elegir el arc\u00f3n perfecto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.expomaquinaria.es\/wpblog\/2016\/11\/21\/arcon-congelador\/","og_locale":"es_ES","og_type":"article","og_title":"Arc\u00f3n congelador - Blog bar - Secretos de Hosteler\u00eda","og_description":"Arc\u00f3n congelador - Las mejores ofertas de arcones congeladores. Te ayudamos a elegir tu arc\u00f3n congelador!! Consejos b\u00e1sicos para elegir el arc\u00f3n perfecto.","og_url":"https:\/\/www.expomaquinaria.es\/wpblog\/2016\/11\/21\/arcon-congelador\/","og_site_name":"Blog hosteleria - Secretos de Hosteler\u00eda","article_publisher":"https:\/\/www.facebook.com\/expomaquinaria","article_author":"https:\/\/www.facebook.com\/expomaquinaria","article_published_time":"2016-11-21T08:30:33+00:00","article_modified_time":"2016-11-21T08:31:31+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.expomaquinaria.es\/wpblog\/wp-content\/uploads\/2016\/11\/congelador-supermercado-inche1770tc-1.jpg","type":"image\/jpeg"}],"author":"expomaquinaria","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/expomaquinaria","twitter_misc":{"Escrito por":"expomaquinaria","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.expomaquinaria.es\/wpblog\/2016\/11\/21\/arcon-congelador\/","url":"https:\/\/www.expomaquinaria.es\/wpblog\/2016\/11\/21\/arcon-congelador\/","name":"Arc\u00f3n congelador - Blog bar - Secretos de Hosteler\u00eda","isPartOf":{"@id":"https:\/\/www.expomaquinaria.es\/wpblog\/#website"},"datePublished":"2016-11-21T08:30:33+00:00","dateModified":"2016-11-21T08:31:31+00:00","author":{"@id":"https:\/\/www.expomaquinaria.es\/wpblog\/#\/schema\/person\/f46f0b99f244d0a6664d217d9fef2423"},"description":"Arc\u00f3n congelador - Las mejores ofertas de arcones congeladores. Te ayudamos a elegir tu arc\u00f3n congelador!! Consejos b\u00e1sicos para elegir el arc\u00f3n perfecto.","breadcrumb":{"@id":"https:\/\/www.expomaquinaria.es\/wpblog\/2016\/11\/21\/arcon-congelador\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.expomaquinaria.es\/wpblog\/2016\/11\/21\/arcon-congelador\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.expomaquinaria.es\/wpblog\/2016\/11\/21\/arcon-congelador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.expomaquinaria.es\/wpblog\/"},{"@type":"ListItem","position":2,"name":"Arc\u00f3n congelador"}]},{"@type":"WebSite","@id":"https:\/\/www.expomaquinaria.es\/wpblog\/#website","url":"https:\/\/www.expomaquinaria.es\/wpblog\/","name":"Blog hosteleria - Secretos de Hosteler\u00eda","description":"Blog hosteleria, Art\u00edculos y noticias del mundo de la hosteler\u00eda y comercio","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.expomaquinaria.es\/wpblog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.expomaquinaria.es\/wpblog\/#\/schema\/person\/f46f0b99f244d0a6664d217d9fef2423","name":"expomaquinaria","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.expomaquinaria.es\/wpblog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b949b2428b2d8f2987d91552b839aaf?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b949b2428b2d8f2987d91552b839aaf?s=96&d=identicon&r=g","caption":"expomaquinaria"},"description":"Expomaquinaria - \"Pasi\u00f3n por la Hosteler\u00eda\", somos un conjunto de profesionales con mas de 30 a\u00f1os de experiencia en el sector de la hosteler\u00eda y comercio. Nos gusta nuestro trabajo y siempre estamos dispuestos a escucharte y asesorarte en lo que necesites.","sameAs":["https:\/\/www.expomaquinaria.es","https:\/\/www.facebook.com\/expomaquinaria","https:\/\/twitter.com\/https:\/\/twitter.com\/expomaquinaria"]}]}},"_links":{"self":[{"href":"https:\/\/www.expomaquinaria.es\/wpblog\/wp-json\/wp\/v2\/posts\/3250"}],"collection":[{"href":"https:\/\/www.expomaquinaria.es\/wpblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expomaquinaria.es\/wpblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expomaquinaria.es\/wpblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expomaquinaria.es\/wpblog\/wp-json\/wp\/v2\/comments?post=3250"}],"version-history":[{"count":0,"href":"https:\/\/www.expomaquinaria.es\/wpblog\/wp-json\/wp\/v2\/posts\/3250\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expomaquinaria.es\/wpblog\/wp-json\/wp\/v2\/media\/3259"}],"wp:attachment":[{"href":"https:\/\/www.expomaquinaria.es\/wpblog\/wp-json\/wp\/v2\/media?parent=3250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expomaquinaria.es\/wpblog\/wp-json\/wp\/v2\/categories?post=3250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expomaquinaria.es\/wpblog\/wp-json\/wp\/v2\/tags?post=3250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}